{"id":20567,"date":"2023-05-18T17:30:58","date_gmt":"2023-05-18T17:30:58","guid":{"rendered":"https:\/\/vibetrace.com\/?p=20567"},"modified":"2023-07-11T16:15:53","modified_gmt":"2023-07-11T16:15:53","slug":"items-per-order","status":"publish","type":"post","link":"https:\/\/vibetrace.com\/it\/articoli-per-ordine\/","title":{"rendered":"Articoli per ordine"},"content":{"rendered":"<div id=\"bsf_rt_marker\"><\/div>\n<p class=\"wp-block-paragraph\">Articoli per ordine \u00e8 una metrica di vendita che fornisce informazioni dettagliate sulle attivit\u00e0 e sul comportamento dei clienti.<\/p>\n\n\n<style>.kb-table-of-content-nav.kb-table-of-content-id_3ed1ed-6c .kb-table-of-content-wrap{padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-right:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);padding-left:var(--global-kb-spacing-sm, 1.5rem);}.kb-table-of-content-nav.kb-table-of-content-id_3ed1ed-6c .kb-table-of-contents-title-wrap{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kb-table-of-content-nav.kb-table-of-content-id_3ed1ed-6c .kb-table-of-contents-title{font-weight:regular;font-style:normal;}.kb-table-of-content-nav.kb-table-of-content-id_3ed1ed-6c .kb-table-of-content-wrap .kb-table-of-content-list{font-weight:regular;font-style:normal;margin-top:var(--global-kb-spacing-sm, 1.5rem);margin-right:0px;margin-bottom:0px;margin-left:0px;}<\/style>\n\n\n<p class=\"wp-block-paragraph\">Nel mondo dell&#039;e-commerce, la maggior parte delle aziende \u00e8 costantemente alla ricerca di modi per aumentare le proprie entrate e la propria redditivit\u00e0.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le aziende di e-commerce possono ottenere informazioni preziose sul comportamento dei clienti e prendere decisioni basate sui dati per ottimizzare le strategie di vendita e di marketing.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ulteriori informazioni sull&#039;importanza degli articoli per ordine, sul relativo calcolo e su come utilizzare questa metrica per migliorare le prestazioni dell&#039;e-commerce.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Che cos&#039;\u00e8 Articoli per ordine?<\/h2>\n\n\n<div class=\"gb-container gb-container-e183e0de\"><div class=\"gb-inside-container\">\n\n<p class=\"gb-headline gb-headline-a0f29df1 gb-headline-text\">Definizione di Articoli per ordine<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Gli articoli per ordine si riferiscono al numero medio di articoli acquistati in una singola transazione o ordine.<\/p>\n\n<\/div><\/div>\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Questa metrica \u00e8 comunemente utilizzata nei settori della vendita al dettaglio e dell&#039;e-commerce per comprendere il comportamento di acquisto dei clienti e misurare l&#039;efficacia degli sforzi di marketing e vendita.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ad esempio, se un cliente effettua un ordine per tre articoli, la metrica &quot;articoli per ordine&quot; per quella transazione \u00e8 3.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">La metrica Articoli per ordine \u00e8 uguale a Unit\u00e0 per transazione?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">\u201c<strong>Articoli per ordine<\/strong>&quot; E &quot;<strong>unit\u00e0 per transazione<\/strong>&quot; sono generalmente la stessa metrica e vengono utilizzati in modo intercambiabile per fare riferimento al numero di articoli venduti in una singola transazione.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entrambi rappresentano il numero di prodotti o unit\u00e0 acquistati in un singolo ordine o transazione.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tuttavia, in alcuni casi, \u201c<strong>unit\u00e0 per transazione<\/strong>&quot; pu\u00f2 riferirsi specificamente al numero di unit\u00e0 fisiche vendute (ad esempio, singoli articoli o prodotti), mentre &quot;<strong>articoli per ordine<\/strong>&quot;pu\u00f2 includere sia articoli fisici che articoli digitali (ad es. ebook, download di musica) o altri articoli immateriali venduti in un singolo ordine o transazione.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Valore pi\u00f9 elevato degli articoli per ordine:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Di solito questo ha un valore del carrello abbandonato pi\u00f9 alto<\/li>\n\n\n\n<li>C&#039;\u00e8 una maggiore possibilit\u00e0 di aumentare la fidelizzazione dei clienti.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Indipendentemente dalla terminologia specifica utilizzata, la metrica \u00e8 importante da tenere traccia in quanto fornisce informazioni sul comportamento del cliente e pu\u00f2 aiutare a definire strategie per aumentare le entrate per transazione.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Articoli per formula ordine<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">La formula per calcolare gli articoli per ordine \u00e8:<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"512\" src=\"https:\/\/vibetrace.com\/wp-content\/uploads\/2023\/03\/items-per-order-formula-1024x512.png\" alt=\"\" class=\"wp-image-20569\" srcset=\"https:\/\/vibetrace.com\/wp-content\/uploads\/2023\/03\/items-per-order-formula-1024x512.png 1024w, https:\/\/vibetrace.com\/wp-content\/uploads\/2023\/03\/items-per-order-formula-300x150.png 300w, https:\/\/vibetrace.com\/wp-content\/uploads\/2023\/03\/items-per-order-formula-768x384.png 768w, https:\/\/vibetrace.com\/wp-content\/uploads\/2023\/03\/items-per-order-formula-18x9.png 18w, https:\/\/vibetrace.com\/wp-content\/uploads\/2023\/03\/items-per-order-formula.png 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Ad esempio, se hai venduto 100 articoli in un giorno tramite 25 ordini, gli articoli per ordine sarebbero:<\/p>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\"><strong>Articoli per ordine = 100 \/ 25 = 4<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ci\u00f2 significa che, in media, i clienti acquistano 4 articoli per ordine.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Articoli per ordine per settore<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Ecco la media degli articoli per ordine per settore:<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/vibetrace.com\/wp-content\/uploads\/2023\/03\/items-per-order-by-industry-1024x1024.png\" alt=\"\" class=\"wp-image-20570\" srcset=\"https:\/\/vibetrace.com\/wp-content\/uploads\/2023\/03\/items-per-order-by-industry-1024x1024.png 1024w, https:\/\/vibetrace.com\/wp-content\/uploads\/2023\/03\/items-per-order-by-industry-300x300.png 300w, https:\/\/vibetrace.com\/wp-content\/uploads\/2023\/03\/items-per-order-by-industry-150x150.png 150w, https:\/\/vibetrace.com\/wp-content\/uploads\/2023\/03\/items-per-order-by-industry-768x768.png 768w, https:\/\/vibetrace.com\/wp-content\/uploads\/2023\/03\/items-per-order-by-industry-12x12.png 12w, https:\/\/vibetrace.com\/wp-content\/uploads\/2023\/03\/items-per-order-by-industry.png 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Fonte: rendimento da dividendi<\/figcaption><\/figure>\n<\/div>\n\n\n<figure class=\"wp-block-table\"><table><tbody><tr><td><strong>Industria&nbsp;<\/strong><\/td><td><strong>Articoli per ordine<\/strong><\/td><\/tr><tr><td>Prodotti alimentari e bevande<\/td><td>7.16<\/td><\/tr><tr><td>Vendita al dettaglio multimarca<\/td><td>5.29<\/td><\/tr><tr><td>Casa e mobili<\/td><td>4.13<\/td><\/tr><tr><td>Bellezza e cura personale<\/td><td>3.79<\/td><\/tr><tr><td>Cura degli animali domestici e servizi veterinari<\/td><td>3.74<\/td><\/tr><tr><td>Lusso e gioielli<\/td><td>3.42<\/td><\/tr><tr><td>Beni di consumo<\/td><td>3.24<\/td><\/tr><tr><td>Moda, accessori e abbigliamento<\/td><td>2.46<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Gli ultimi dati di <a href=\"https:\/\/marketing.dynamicyield.com\/benchmarks\/units-per-transaction\/\" target=\"_blank\" rel=\"noopener\">rendimento del dividendo <\/a>a partire da febbraio 2023 fornisce approfondimenti sugli articoli medi per ordine per settore.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Come mostrato nella tabella, i settori inclusi nei dati sono bellezza e cura della persona, casa e arredamento, cibo e bevande, cura degli animali e servizi veterinari, vendita al dettaglio multimarca, moda, accessori e abbigliamento, beni di consumo e beni di lusso e gioielleria.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">I dati mostrano che l&#039;industria alimentare e delle bevande ha gli articoli medi pi\u00f9 alti per ordine a 7,16, indicando che i clienti tendono ad acquistare pi\u00f9 articoli in un unico ordine quando acquistano cibo e bevande.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Anche la casa e l&#039;arredamento e la vendita al dettaglio multimarca hanno una media elevata di articoli per ordine rispettivamente a 4,13 e 5,29, suggerendo che i clienti tendono ad acquistare diversi articoli quando acquistano articoli per la casa o da una variet\u00e0 di marchi.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">D&#039;altra parte, l&#039;industria della moda, degli accessori e dell&#039;abbigliamento ha una media relativamente bassa di articoli per ordine pari a 2,46, il che indica che i clienti tendono ad acquistare meno articoli in un singolo ordine quando acquistano abbigliamento e accessori.&nbsp;<\/p>\n\n\n<div class=\"gb-container gb-container-0d1ad9b9\"><div class=\"gb-inside-container\">\n\n<div class=\"gb-headline gb-headline-1b53429c gb-headline-text\">Hai bisogno di aiuto con Ecommerce Analytics?<\/div>\n\n\n\n<div class=\"gb-headline gb-headline-28ab0524 gb-headline-text\">Prova il nostro strumento gratuitamente per vedere come le nostre funzionalit\u00e0 di analisi dell&#039;e-commerce ti aiuteranno a gestire le tue campagne di marketing in un modo molto migliore.<\/div>\n\n\n<div class=\"gb-button-wrapper gb-button-wrapper-2ba3f4d1\">\n\n<a class=\"gb-button gb-button-3046ca2a gb-button-text vt-register vt-track-click\" href=\"https:\/\/vibetrace.com\/it\/software-di-analisi-e-commerce\/\">Saperne di pi\u00f9<\/a>\n\n<\/div>\n<\/div><\/div>\n\n\n<p class=\"wp-block-paragraph\">Gli altri settori nei dati, tra cui bellezza e cura della persona, cura degli animali domestici e servizi veterinari, beni di consumo, lusso e gioielli, si collocano tra questi intervalli.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Questi dati identificano preziose informazioni sul comportamento di acquisto dei clienti in diversi settori e possono aiutarti a comprendere le aspettative dei tuoi clienti e ottimizzare di conseguenza le loro strategie di vendita e marketing.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Come monitorare gli articoli per ordine?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Il monitoraggio regolare degli articoli per ordine pu\u00f2 aiutarti a prendere decisioni basate sui dati per migliorare le prestazioni del tuo e-commerce.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sono disponibili diversi strumenti per tenere traccia degli articoli per ordine. Ecco alcune opzioni:<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/vibetrace.com\/wp-content\/uploads\/2023\/03\/track-items-per-order-1-1024x1024.png\" alt=\"\" class=\"wp-image-20573\" srcset=\"https:\/\/vibetrace.com\/wp-content\/uploads\/2023\/03\/track-items-per-order-1-1024x1024.png 1024w, https:\/\/vibetrace.com\/wp-content\/uploads\/2023\/03\/track-items-per-order-1-300x300.png 300w, https:\/\/vibetrace.com\/wp-content\/uploads\/2023\/03\/track-items-per-order-1-150x150.png 150w, https:\/\/vibetrace.com\/wp-content\/uploads\/2023\/03\/track-items-per-order-1-768x768.png 768w, https:\/\/vibetrace.com\/wp-content\/uploads\/2023\/03\/track-items-per-order-1-12x12.png 12w, https:\/\/vibetrace.com\/wp-content\/uploads\/2023\/03\/track-items-per-order-1.png 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Statistiche di Google: <\/strong>Google Analytics \u00e8 un servizio di analisi web gratuito per il monitoraggio delle transazioni di e-commerce, inclusi gli articoli per ordine. Puoi utilizzare Google Analytics per monitorare il numero di articoli acquistati in ogni transazione e altre metriche correlate come il valore medio dell&#039;ordine abilitando il monitoraggio dell&#039;e-commerce sul tuo sito web.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Shopify: <\/strong>Shopify \u00e8 una piattaforma di e-commerce che fornisce analisi integrate per tenere traccia delle metriche chiave, inclusi gli articoli per ordine. Il dashboard di analisi fornisce una visione dettagliata delle prestazioni del tuo negozio e puoi eseguire il drill-down per visualizzare metriche come la media degli articoli per ordine.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Questi sono solo alcuni dei numerosi strumenti disponibili per tenere traccia degli articoli per ordine. A seconda delle tue esigenze e del tuo budget, potresti voler esplorare anche altre opzioni.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Con che frequenza dovresti controllare la metrica Articoli per ordine?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">La frequenza del controllo degli articoli per metrica dell&#039;ordine dipende dalle dimensioni della tua attivit\u00e0 e dal volume delle transazioni.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">In generale, \u00e8 buona norma monitorare questa metrica su base regolare, ad esempio<strong> giornaliero, settimanale o mensile<\/strong>, per tenere traccia dei cambiamenti nel comportamento dei clienti e identificare le tendenze nel tempo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Giornaliero o Settimanale: <\/strong>Se hai una piccola impresa con volumi di transazioni inferiori, il controllo degli articoli per ordine su base giornaliera o settimanale pu\u00f2 essere sufficiente per ottenere informazioni sul comportamento dei clienti e apportare modifiche alle strategie di vendita e di marketing.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Mensile<\/strong>: Se non hai grandi variazioni tra settimane o stagioni, dovrebbe essere sufficiente un controllo mensile.<\/p>\n\n\n<div class=\"gb-container gb-container-bc53bdfe\"><div class=\"gb-inside-container\">\n\n<div class=\"gb-headline gb-headline-c8c301d0 gb-headline-text\">Hai bisogno di aiuto per aumentare il tasso di conversione?<\/div>\n\n\n\n<div class=\"gb-headline gb-headline-4032ca8d gb-headline-text\">Scopri come aumentare il tasso di conversione con decisioni intelligenti basate sui dati e utilizzando il software di automazione del marketing.<\/div>\n\n\n<div class=\"gb-button-wrapper gb-button-wrapper-3bc9c6f2\">\n\n<a class=\"gb-button gb-button-16e8d80b gb-button-text vt-register vt-track-click\" href=\"https:\/\/vibetrace.com\/it\/aumentare-tasso-di-conversione\/\">Aumenta la conversione<\/a>\n\n<\/div>\n<\/div><\/div>\n\n\n<h2 class=\"wp-block-heading\">Articoli per calcolatore dell&#039;ordine<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Vuoi calcolare i tuoi Articoli per Ordine? Usa il nostro semplice calcolatore qui sotto.<\/p>\n\n\n<div class=\"gb-container gb-container-ae3b4f52 simple-calculator\">\n\n<h3 class=\"wp-block-heading\" id=\"calculator\" style=\"font-size:32px\"><strong>Articoli semplici per calcolatore di ordine<\/strong><\/h3>\n\n\n<div class=\"gb-grid-wrapper gb-grid-wrapper-4307aaaf\">\n<div class=\"gb-grid-column gb-grid-column-8af595c2\"><div class=\"gb-container gb-container-8af595c2\">\n\n<p class=\"has-small-font-size wp-block-paragraph\" style=\"letter-spacing:0px\">Numero di articoli acquistati:<\/p>\n\n\n\n<input type=\"number\" min=\"0\" value=\"120\" id=\"input_calc1\" class=\"input\" required=\"\">\n\n\n\n<p class=\"has-small-font-size wp-block-paragraph\">Numero di ordini<\/p>\n\n\n\n<input type=\"number\" min=\"0\" value=\"70\" id=\"input_calc2\" class=\"input\" required=\"\">\n\n\n\n<span class=\"gb-button gb-button-59cfcaac gb-button-text\" onclick=\"calculateResult();\">Calcolare<\/span>\n\n<\/div><\/div>\n\n<div class=\"gb-grid-column gb-grid-column-e762286a\"><div class=\"gb-container gb-container-e762286a\">\n\n<h5 class=\"wp-block-heading has-text-align-center\"><strong>Articoli per ordine<\/strong><\/h5>\n\n\n\n<p class=\"gb-headline gb-headline-864a3611 gb-headline-text\" id=\"result_html\">= ?<\/p>\n\n\n\n<script>\n      function calculateResult() {\n        var calc1 = document.getElementById('input_calc1').value;\n        var calc2 = document.getElementById('input_calc2').value;\n        var result = (calc1 \/ calc2).toFixed(2);\n        document.getElementById('result_html').innerHTML = result + '';\n      }\n    <\/script>\n\n<\/div><\/div>\n<\/div>\n<\/div>\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Cose importanti sugli articoli per ordine<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Ecco alcune cose importanti da tenere a mente sugli articoli per ordine:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Varia per categoria di prodotto:<\/strong> Gli articoli per ordine possono variare in base al tipo di merce venduta. Ad esempio, i clienti possono acquistare pi\u00f9 prodotti elettronici in un unico ordine di articoli di consumo a basso costo come articoli da toeletta ma meno articoli di articoli di alto valore come l&#039;elettronica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Influisce sul valore medio dell&#039;ordine: <\/strong>La variazione degli articoli per ordine \u00e8 una considerazione importante quando si calcola il valore medio dell&#039;ordine (AOV). Puoi aumentare il tuo AOV e creare pi\u00f9 entrate per ogni transazione aumentando il numero di articoli per ordine.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Influenzato da promozioni e sconti:<\/strong> Offrire promozioni e sconti, come paghi uno prendi due o la spedizione gratuita per ordini superiori a un determinato importo, attirer\u00e0 i tuoi clienti ad acquistare pi\u00f9 cose in una singola transazione, aumentando la metrica degli articoli per ordine.<\/p>\n\n\n<div class=\"gb-container gb-container-4fe8fb59\"><div class=\"gb-inside-container\">\n<div class=\"gb-grid-wrapper gb-grid-wrapper-4e3009e9\">\n<div class=\"gb-grid-column gb-grid-column-2156c324\"><div class=\"gb-container gb-container-2156c324\"><div class=\"gb-inside-container\">\n\n<p class=\"gb-headline gb-headline-becb76a4 gb-headline-text\">Ti piace questo articolo?<\/p>\n\n\n\n<p class=\"gb-headline gb-headline-d0253076 gb-headline-text\">Iscriviti alla nostra newsletter dedicata alla CX for Retail!<\/p>\n\n\n<div class=\"gb-container gb-container-d5704067\"><div class=\"gb-inside-container\">\n<div class=\"wp-block-image is-style-rounded\">\n<figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/vibetrace.com\/wp-content\/uploads\/2022\/11\/female_avg-1024x1024.jpeg\" alt=\"\" class=\"wp-image-15727\" style=\"width:188px;height:188px\" srcset=\"https:\/\/vibetrace.com\/wp-content\/uploads\/2022\/11\/female_avg.jpeg 1024w, https:\/\/vibetrace.com\/wp-content\/uploads\/2022\/11\/female_avg-300x300.jpeg 300w, https:\/\/vibetrace.com\/wp-content\/uploads\/2022\/11\/female_avg-150x150.jpeg 150w, https:\/\/vibetrace.com\/wp-content\/uploads\/2022\/11\/female_avg-768x768.jpeg 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n<\/div><\/div>\n\n\n<p class=\"gb-headline gb-headline-ef94572a gb-headline-text\">Rimani connesso a ci\u00f2 che \u00e8 veramente importante per ottimizzare i tuoi ricavi digitali.<\/p>\n\n\n\n<form style=\"width:100%; display:block; text-align:center; margin:0px auto 20px auto\" action=\"https:\/\/pages.vtcdn.net\/lists\/213\/2626\/0MOEaLRBEknB\/subscribe\" name=\"blue_woman\" method=\"POST\" target=\"_blank\">\n<div style=\"width:100%; margin:10px 0\"><input style=\"width:100%\" type=\"text\" name=\"email\" value=\"\" placeholder=\"Indirizzo e-mail\"><\/div>\n<div style=\"width:100%; margin:10px 0\"><input style=\"width:100%\" type=\"text\" name=\"firstname\" value=\"\" placeholder=\"Nome di battesimo\"><\/div>\n<input type=\"hidden\" name=\"source\" value=\"blog_blue_woman\">\n<input type=\"text\" name=\"__em\" value=\"\" style=\"display:none\">\n<input type=\"text\" name=\"__email\" value=\"\" style=\"display:none\">\n<input type=\"text\" name=\"__name\" value=\"\" style=\"display:none\">\n<div class=\"gb-button-wrapper\">\n<button type=\"submit\" class=\"gb-button gb-button-text\" style=\"width:100%\">Iscriviti a me<\/button>\n<\/div>\n<\/form>\n\n\n\n<p class=\"has-small-font-size wp-block-paragraph\">Cliccando sul pulsante accetti la nostra <a rel=\"noreferrer noopener\" href=\"https:\/\/vibetrace.com\/it\/termini-e-condizioni\/\" target=\"_blank\">Termini &amp; Condizioni<\/a>. Inoltre dovrai confermare il tuo indirizzo email.<\/p>\n\n<\/div><\/div><\/div>\n<\/div>\n<\/div><\/div>\n\n\n<p class=\"wp-block-paragraph\"><strong>Utilizzato per segmentare i clienti: <\/strong>\u00c8 possibile identificare i gruppi di clienti che preferiscono acquistare pi\u00f9 articoli in un unico ordine valutando gli articoli in base ai dati dell&#039;ordine. Questo pu\u00f2 essere utilizzato per informare gli sforzi di marketing e vendita mirati per aumentare il numero di articoli per ordine e le entrate complessive della tua azienda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Rivelare le inefficienze operative:<\/strong> I clienti che effettuano diversi ordini con solo pochi articoli per ordine possono suggerire inefficienze operative come costi di spedizione elevati o tempi di consegna lenti. Affrontare questi problemi pu\u00f2 aumentare la soddisfazione del cliente e aumentare il numero di articoli per ordine.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">In poche parole, Articoli per ordine \u00e8 una metrica preziosa che pu\u00f2 fornire informazioni sul comportamento dei clienti e informare il processo decisionale strategico per le aziende di e-commerce.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Metriche relative agli articoli per ordine<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Esistono diverse metriche relative agli articoli per ordine che potresti voler monitorare:<\/p>\n\n\n<div class=\"gb-container gb-container-f80d3d7f\"><div class=\"gb-inside-container\">\n<div class=\"gb-grid-wrapper gb-grid-wrapper-a56ca273\">\n<div class=\"gb-grid-column gb-grid-column-664deae2\"><div class=\"gb-container gb-container-664deae2\"><div class=\"gb-inside-container\">\n<div class=\"gb-container gb-container-41d958d5\"><div class=\"gb-inside-container\">\n\n<h4 class=\"gb-headline gb-headline-f61fbe0b gb-headline-text\"><strong>Valore a vita del cliente<\/strong><\/h4>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/vibetrace.com\/it\/valore-per-tutta-la-vita-del-cliente\/\" data-type=\"post\" data-id=\"18989\">Il valore totale stimato di un cliente per un&#039;azienda nel corso della sua vita<\/a><\/p>\n\n<\/div><\/div>\n<\/div><\/div><\/div>\n\n<div class=\"gb-grid-column gb-grid-column-e76bfbfb\"><div class=\"gb-container gb-container-e76bfbfb\"><div class=\"gb-inside-container\">\n<div class=\"gb-container gb-container-92fc2757\"><div class=\"gb-inside-container\">\n\n<h4 class=\"gb-headline gb-headline-b27a665c gb-headline-text\"><strong>Tasso di acquisto ripetuto<\/strong><\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">La percentuale di clienti che effettuano pi\u00f9 di un acquisto dal tuo sito web.<\/p>\n\n<\/div><\/div>\n<\/div><\/div><\/div>\n\n<div class=\"gb-grid-column gb-grid-column-f2770bcb\"><div class=\"gb-container gb-container-f2770bcb\"><div class=\"gb-inside-container\">\n<div class=\"gb-container gb-container-2cdb91c0\"><div class=\"gb-inside-container\">\n\n<h4 class=\"gb-headline gb-headline-57b7f460 gb-headline-text\"><strong>Tasso di conversione<\/strong><\/h4>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/vibetrace.com\/it\/tasso-di-conversione\/\" data-type=\"post\" data-id=\"17496\">Il numero di conversioni (come l&#039;effettuazione di un acquisto o la compilazione di un modulo) risultanti dalla campagna e-mail, diviso per il numero di e-mail consegnate.<\/a><\/p>\n\n<\/div><\/div>\n<\/div><\/div><\/div>\n<\/div>\n\n<div class=\"gb-grid-wrapper gb-grid-wrapper-a35c039c\">\n<div class=\"gb-grid-column gb-grid-column-ed88f7ec\"><div class=\"gb-container gb-container-ed88f7ec\"><div class=\"gb-inside-container\">\n<div class=\"gb-container gb-container-4be5881c\"><div class=\"gb-inside-container\">\n\n<h4 class=\"gb-headline gb-headline-367efc9a gb-headline-text\"><strong>Tempo sul sito<\/strong><\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">La quantit\u00e0 di tempo che i visitatori trascorrono sul tuo sito web.<\/p>\n\n<\/div><\/div>\n<\/div><\/div><\/div>\n\n<div class=\"gb-grid-column gb-grid-column-597d63b3\"><div class=\"gb-container gb-container-597d63b3\"><div class=\"gb-inside-container\">\n<div class=\"gb-container gb-container-f2770bcb\"><div class=\"gb-inside-container\">\n\n<h4 class=\"gb-headline gb-headline-af6fafea gb-headline-text\"><strong>Valore medio dell&#039;ordine<\/strong><\/h4>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/vibetrace.com\/it\/valore-medio-dellordine\/\" data-type=\"post\" data-id=\"17832\">L&#039;importo medio speso per transazione<\/a><\/p>\n\n<\/div><\/div>\n<\/div><\/div><\/div>\n\n<div class=\"gb-grid-column gb-grid-column-6bc6fe88\"><div class=\"gb-container gb-container-6bc6fe88\"><div class=\"gb-inside-container\">\n<div class=\"gb-container gb-container-4be5881c\"><div class=\"gb-inside-container\">\n\n<h4 class=\"gb-headline gb-headline-367efc9a gb-headline-text\"><strong>Ritorno sull&#039;investimento di marketing<\/strong><\/h4>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/vibetrace.com\/it\/ritorno-sugli-investimenti-di-marketing\/\" data-type=\"post\" data-id=\"19507\">Il ritorno sull&#039;investimento in una campagna di marketing o pubblicitaria<\/a><\/p>\n\n<\/div><\/div>\n<\/div><\/div><\/div>\n<\/div>\n<\/div><\/div>\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con la giusta strategia, sarai in grado di aumentare gli ordini dei tuoi clienti sul tuo sito web, ma devi anche prendere atto che \u00e8 una buona opzione per semplificare il tuo lavoro nella promozione della tua attivit\u00e0 attraverso un&#039;adeguata automazione.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Vibetrace \u00e8 qui per aiutarti a raggiungere i tuoi obiettivi con la potenza di un<strong> strumento di email marketing con tonnellate di modelli prontamente disponibili<\/strong> per la tua e-mail personalizzata per mantenere i clienti coinvolti nell&#039;acquisto di pi\u00f9 articoli attraverso l&#039;upselling e il cross-selling.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Unisciti alla mailing list di Vibetrace e scopri informazioni e aggiornamenti pi\u00f9 preziosi!<\/p>","protected":false},"excerpt":{"rendered":"<p>Articoli per ordine \u00e8 una metrica di vendita che fornisce informazioni dettagliate sulle attivit\u00e0 e sul comportamento dei clienti. \u2026 <a title=\"Articoli per ordine\" class=\"read-more\" href=\"https:\/\/vibetrace.com\/it\/articoli-per-ordine\/\" aria-label=\"Per saperne di pi\u00f9 su Articoli per Ordine\"> <\/a><\/p>","protected":false},"author":8,"featured_media":20574,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[83],"tags":[57,89,102],"class_list":["post-20567","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-metrics-kpis","tag-marketing-definitions","tag-level2","tag-marketing-metrics","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50"],"_links":{"self":[{"href":"https:\/\/vibetrace.com\/it\/wp-json\/wp\/v2\/posts\/20567","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vibetrace.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vibetrace.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vibetrace.com\/it\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/vibetrace.com\/it\/wp-json\/wp\/v2\/comments?post=20567"}],"version-history":[{"count":0,"href":"https:\/\/vibetrace.com\/it\/wp-json\/wp\/v2\/posts\/20567\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vibetrace.com\/it\/wp-json\/wp\/v2\/media\/20574"}],"wp:attachment":[{"href":"https:\/\/vibetrace.com\/it\/wp-json\/wp\/v2\/media?parent=20567"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vibetrace.com\/it\/wp-json\/wp\/v2\/categories?post=20567"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vibetrace.com\/it\/wp-json\/wp\/v2\/tags?post=20567"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}