{"id":26343,"date":"2024-07-05T15:58:42","date_gmt":"2024-07-05T15:58:42","guid":{"rendered":"https:\/\/vibetrace.com\/?p=26343"},"modified":"2024-07-06T16:03:09","modified_gmt":"2024-07-06T16:03:09","slug":"introducing-attribute-preview-gain-instant-insights-into-your-customer-data","status":"publish","type":"post","link":"https:\/\/vibetrace.com\/de\/einfuhrung-der-attributvorschau-erhalten-sie-sofortige-einblicke-in-ihre-kundendaten\/","title":{"rendered":"Einf\u00fchrung der Attributvorschau: Erhalten Sie sofortige Einblicke in Ihre Kundendaten"},"content":{"rendered":"<div id=\"bsf_rt_marker\"><\/div>\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">In der heutigen datengesteuerten Welt kann der schnelle und einfache Zugriff auf genaue Kundeninformationen \u00fcber Erfolg oder Misserfolg Ihrer Marketingstrategie entscheiden. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Wenn Sie Zugriff auf die wichtigsten Attribute Ihrer Kundendaten in der Vorschau haben, k\u00f6nnen Sie im Handumdrehen fundierte Entscheidungen treffen. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mit unserem neuen <strong>Attributvorschau-Funktion<\/strong>k\u00f6nnen Sie genau das tun: Ihren Arbeitsablauf optimieren, Ihre Erkenntnisse verbessern und die Effektivit\u00e4t Ihrer Kampagne wie nie zuvor steigern.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Haben Sie sich als Vermarkter schon einmal gefragt:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Welche Werte legen wir auf den Ort bzw. die Stadt?<\/li>\n\n\n\n<li>Welche Werte haben wir f\u00fcr die Originalquelle?<\/li>\n\n\n\n<li>Dasselbe gilt f\u00fcr andere benutzerdefinierte Attribute<\/li>\n<\/ul>\n\n\n<div class=\"gb-container gb-container-14ed92c3\"><div class=\"gb-inside-container\">\n\n<div class=\"gb-headline gb-headline-b1978215 gb-headline-text\">Ben\u00f6tigen Sie Hilfe bei Ihrer Kundendatenplattform?<\/div>\n\n\n\n<div class=\"gb-headline gb-headline-3a57dbeb gb-headline-text\">Die Kundendatenbank ist die Basis f\u00fcr erfolgreiche Marketingkampagnen. Lassen Sie uns Ihnen zeigen, was wir tun k\u00f6nnen, um Kundenbindung und Einnahmen zu steigern.<\/div>\n\n\n<div class=\"gb-button-wrapper gb-button-wrapper-d6d31736\">\n\n<a class=\"gb-button gb-button-8e1191c7 gb-button-text vt-contact vt-track-click\" href=\"https:\/\/vibetrace.com\/de\/kundendatenplattform\/\">Erfahren Sie mehr<\/a>\n\n<\/div>\n<\/div><\/div>\n\n\n<p class=\"wp-block-paragraph\">Wir haben eine sehr einfache M\u00f6glichkeit hinzugef\u00fcgt, Werte in der Datenplattform in der Vorschau anzuzeigen. Diese Werte k\u00f6nnen verschiedene Quellen haben:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Benutzerereignisse und -aktivit\u00e4t<\/li>\n\n\n\n<li>Bestellungen &amp; Transaktionen<\/li>\n\n\n\n<li>externe APIs und Datensynchronisation<\/li>\n\n\n\n<li>manuelle Updates<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Vibetrace wird angetrieben durch eine starke <a href=\"https:\/\/vibetrace.com\/de\/kundendatenplattform\/\" data-type=\"page\" data-id=\"14230\">Kundendatenplattform<\/a> und eine unserer St\u00e4rken ist eine sehr skalierbare Datenplattform.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sie k\u00f6nnen diese Werte f\u00fcr Folgendes verwenden:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/vibetrace.com\/de\/kundensegmentierung-2\/\" data-type=\"page\" data-id=\"24126\">Benutzersegmentierung<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/vibetrace.com\/de\/web-personalisierungssoftware\/\" data-type=\"page\" data-id=\"14370\">Personalisierung<\/a> (Omni-Channel-Personalisierung)<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">Die L\u00f6sung:<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Zeigen Sie Attributwerte zusammen mit der von Ihnen festgelegten Bedingung direkt in der Benutzersegmentierung in der Vorschau an.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"330\" src=\"https:\/\/vibetrace.com\/wp-content\/uploads\/2024\/07\/image-1-1024x330.png\" alt=\"\" class=\"wp-image-26345\" srcset=\"https:\/\/vibetrace.com\/wp-content\/uploads\/2024\/07\/image-1-1024x330.png 1024w, https:\/\/vibetrace.com\/wp-content\/uploads\/2024\/07\/image-1-300x97.png 300w, https:\/\/vibetrace.com\/wp-content\/uploads\/2024\/07\/image-1-768x247.png 768w, https:\/\/vibetrace.com\/wp-content\/uploads\/2024\/07\/image-1-1536x495.png 1536w, https:\/\/vibetrace.com\/wp-content\/uploads\/2024\/07\/image-1-2048x660.png 2048w, https:\/\/vibetrace.com\/wp-content\/uploads\/2024\/07\/image-1-18x6.png 18w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Zeigen Sie Werte in der Liste der Datenattribute f\u00fcr die gesamte Plattform in der Vorschau an.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"191\" src=\"https:\/\/vibetrace.com\/wp-content\/uploads\/2024\/07\/image-1024x191.png\" alt=\"\" class=\"wp-image-26344\" srcset=\"https:\/\/vibetrace.com\/wp-content\/uploads\/2024\/07\/image-1024x191.png 1024w, https:\/\/vibetrace.com\/wp-content\/uploads\/2024\/07\/image-300x56.png 300w, https:\/\/vibetrace.com\/wp-content\/uploads\/2024\/07\/image-768x143.png 768w, https:\/\/vibetrace.com\/wp-content\/uploads\/2024\/07\/image-18x3.png 18w, https:\/\/vibetrace.com\/wp-content\/uploads\/2024\/07\/image.png 1254w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Wenn Sie auf die Schaltfl\u00e4che klicken, wird ein Modalfenster mit bis zu 200 Werten f\u00fcr dieses bestimmte Attribut angezeigt:<\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"908\" height=\"1024\" src=\"https:\/\/vibetrace.com\/wp-content\/uploads\/2024\/07\/image-2-908x1024.png\" alt=\"\" class=\"wp-image-26346\" style=\"width:553px;height:auto\" srcset=\"https:\/\/vibetrace.com\/wp-content\/uploads\/2024\/07\/image-2-908x1024.png 908w, https:\/\/vibetrace.com\/wp-content\/uploads\/2024\/07\/image-2-266x300.png 266w, https:\/\/vibetrace.com\/wp-content\/uploads\/2024\/07\/image-2-768x866.png 768w, https:\/\/vibetrace.com\/wp-content\/uploads\/2024\/07\/image-2-11x12.png 11w, https:\/\/vibetrace.com\/wp-content\/uploads\/2024\/07\/image-2.png 1238w\" sizes=\"auto, (max-width: 908px) 100vw, 908px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Mit dieser Funktion k\u00f6nnen Sie Zeit sparen und nicht mehr entscheiden, welche Werte Sie verwenden m\u00f6chten, wenn Sie unsere leistungsstarke Benutzersegmentierung \u00fcber alle verf\u00fcgbaren Kan\u00e4le hinweg einsetzen.<\/p>\n\n\n<div class=\"gb-container gb-container-4fe8fb59\"><div class=\"gb-inside-container\">\n<div class=\"gb-grid-wrapper gb-grid-wrapper-4e3009e9\">\n<div class=\"gb-grid-column gb-grid-column-2156c324\"><div class=\"gb-container gb-container-2156c324\"><div class=\"gb-inside-container\">\n\n<p class=\"gb-headline gb-headline-becb76a4 gb-headline-text\">M\u00f6chten Sie in Sachen Marketing auf dem Laufenden bleiben?<\/p>\n\n\n\n<p class=\"gb-headline gb-headline-d0253076 gb-headline-text\">Abonnieren Sie unseren Retail CX-Newsletter!<\/p>\n\n\n<div class=\"gb-container gb-container-d5704067\"><div class=\"gb-inside-container\">\n<div class=\"wp-block-image is-style-rounded\">\n<figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/vibetrace.com\/wp-content\/uploads\/2023\/01\/image-2-1024x1024.png\" alt=\"\" class=\"wp-image-17448\" style=\"width:237px;height:237px\" srcset=\"https:\/\/vibetrace.com\/wp-content\/uploads\/2023\/01\/image-2.png 1024w, https:\/\/vibetrace.com\/wp-content\/uploads\/2023\/01\/image-2-300x300.png 300w, https:\/\/vibetrace.com\/wp-content\/uploads\/2023\/01\/image-2-150x150.png 150w, https:\/\/vibetrace.com\/wp-content\/uploads\/2023\/01\/image-2-768x768.png 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n<\/div><\/div>\n\n\n<p class=\"gb-headline gb-headline-ef94572a gb-headline-text\">Bleiben Sie in Verbindung mit dem, was wirklich wichtig ist, um Ihre digitalen Einnahmen zu optimieren.<\/p>\n\n\n\n<form style=\"width:100%; display:block; text-align:center; margin:0px auto 20px auto\" action=\"https:\/\/pages.vtcdn.net\/lists\/213\/2626\/0MOEaLRBEknB\/subscribe\" name=\"blue_woman\" method=\"POST\" target=\"_blank\">\n<div style=\"width:100%; margin:10px 0\"><input style=\"width:100%\" type=\"text\" name=\"email\" value=\"\" placeholder=\"E-Mail-Addresse\"><\/div>\n<div style=\"width:100%; margin:10px 0\"><input style=\"width:100%\" type=\"text\" name=\"firstname\" value=\"\" placeholder=\"Vorname\"><\/div>\n<input type=\"hidden\" name=\"source\" value=\"blog_green_man\">\n<input type=\"text\" name=\"__em\" value=\"\" style=\"display:none\">\n<input type=\"text\" name=\"__email\" value=\"\" style=\"display:none\">\n<input type=\"text\" name=\"__name\" value=\"\" style=\"display:none\">\n<div class=\"gb-button-wrapper\">\n<button type=\"submit\" class=\"gb-button gb-button-text\" style=\"width:100%\">Abonniert mich<\/button>\n<\/div>\n<\/form>\n\n\n\n<p class=\"has-small-font-size wp-block-paragraph\">Durch Anklicken des Buttons akzeptieren Sie unsere <a rel=\"noreferrer noopener\" href=\"https:\/\/vibetrace.com\/de\/geschaftsbedingungen\/\" target=\"_blank\">Terms &amp; amp; Bedingungen<\/a>. Au\u00dferdem m\u00fcssen Sie Ihre E-Mail-Adresse best\u00e4tigen.<\/p>\n\n<\/div><\/div><\/div>\n<\/div>\n<\/div><\/div>\n\n\n<p class=\"wp-block-paragraph\"><strong>Anwendungsfall: Verbesserung der Segmentierungspr\u00e4zision<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ein Digital Marketing Manager bei einem mittelgro\u00dfen E-Commerce-Unternehmen muss f\u00fcr eine bevorstehende E-Mail-Kampagne zielgerichtete Segmente erstellen. Mithilfe der Attributvorschaufunktion kann er schnell eine Vorschau der Werte von Kundenattributen wie Kaufhistorie, geografischer Standort und Browsing-Verhalten anzeigen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">So stellen sie beispielsweise fest, dass ein erheblicher Teil ihrer Kunden, die Winterkleidung kaufen, auch nach Outdoor-Ausr\u00fcstung sucht. Mit dieser Erkenntnis erstellen sie ein Kundensegment, das sowohl an Winterkleidung als auch an Outdoor-Ausr\u00fcstung interessiert ist. So stellen sie sicher, dass ihre E-Mail-Kampagne gezielt auf eine Zielgruppe ausgerichtet ist, die eher interessiert ist und sich f\u00fcr eine Conversion entscheidet.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Anwendungsfall: Personalisierung in der Kommunikation verbessern<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ein Customer Experience Manager bei einem abonnementbasierten Dienst m\u00f6chte seine monatlichen Newsletter personalisieren, um die Kundenbindung zu erh\u00f6hen. Mit der Attributvorschaufunktion kann er schnell die neuesten Werte f\u00fcr Attribute wie Abonnementtyp und Benutzereinstellungen \u00fcberpr\u00fcfen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sie identifizieren beispielsweise eine Gruppe von Premium-Abonnenten, die sich h\u00e4ufig mit Inhalten besch\u00e4ftigen, die mit den neu hinzugef\u00fcgten Artikeln in Zusammenhang stehen. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durch die Vorschau dieser Attribute kann der Manager den Newsletter personalisieren, um kommende erweiterte Funktionen und exklusive Tipps hervorzuheben und so eine ma\u00dfgeschneiderte und relevantere Kommunikation zu schaffen, die bei jedem Kunden Anklang findet.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Was denken Sie?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Probieren Sie es mit uns aus. Kontaktieren Sie uns oder erstellen Sie ein Konto, um es noch heute zu nutzen.<\/p>","protected":false},"excerpt":{"rendered":"<p>In der heutigen datengesteuerten Welt kann ein schneller und einfacher Zugriff auf genaue Kundeninformationen von entscheidender Bedeutung sein \u2026 <a title=\"Einf\u00fchrung der Attributvorschau: Erhalten Sie sofortige Einblicke in Ihre Kundendaten\" class=\"read-more\" href=\"https:\/\/vibetrace.com\/de\/einfuhrung-der-attributvorschau-erhalten-sie-sofortige-einblicke-in-ihre-kundendaten\/\" aria-label=\"Weitere Informationen zu Einf\u00fchrung der Attributvorschau: Erhalten Sie sofortige Einblicke in Ihre Kundendaten\"> <\/a><\/p>","protected":false},"author":9,"featured_media":26348,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[91],"tags":[128],"class_list":["post-26343","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-marketing-software","tag-customer-data-platform","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50"],"_links":{"self":[{"href":"https:\/\/vibetrace.com\/de\/wp-json\/wp\/v2\/posts\/26343","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vibetrace.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vibetrace.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vibetrace.com\/de\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/vibetrace.com\/de\/wp-json\/wp\/v2\/comments?post=26343"}],"version-history":[{"count":2,"href":"https:\/\/vibetrace.com\/de\/wp-json\/wp\/v2\/posts\/26343\/revisions"}],"predecessor-version":[{"id":26349,"href":"https:\/\/vibetrace.com\/de\/wp-json\/wp\/v2\/posts\/26343\/revisions\/26349"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vibetrace.com\/de\/wp-json\/wp\/v2\/media\/26348"}],"wp:attachment":[{"href":"https:\/\/vibetrace.com\/de\/wp-json\/wp\/v2\/media?parent=26343"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vibetrace.com\/de\/wp-json\/wp\/v2\/categories?post=26343"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vibetrace.com\/de\/wp-json\/wp\/v2\/tags?post=26343"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}